{"id":537,"date":"2016-04-14T20:07:43","date_gmt":"2016-04-14T20:07:43","guid":{"rendered":"http:\/\/blogs.bard.edu\/arendtcollection\/?p=537"},"modified":"2025-08-11T11:35:51","modified_gmt":"2025-08-11T15:35:51","slug":"schmitt-carl-die-lage-der-europaischen-rechtswissenschaft","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/","title":{"rendered":"Schmitt, Carl &#8211; Die Lage der Europ\u00e4ischen Rechtswissenschaft"},"content":{"rendered":"<p><a href=\"http:\/\/www.bard.edu\/library\/arendt\/pdfs\/Schmitt-Lage.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-808\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen-205x300.png\" alt=\"schmitt-die-lage-der-europaischen\" width=\"205\" height=\"300\" srcset=\"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen-205x300.png 205w, https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png 402w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<h2>Schmitt, Carl<br \/>\n<strong><a href=\"http:\/\/www.bard.edu\/library\/arendt\/pdfs\/Schmitt-Lage.pdf\" target=\"_blank\" rel=\"noopener\">Die Lage der Europ\u00e4ischen Rechtswissenschaft<\/a><\/strong><\/h2>\n<p>T\u00fcbingen, Internationaler Universit\u00e4ts-Verlag, 1950<br \/>\nCall #:\u00a0<a href=\"https:\/\/bardcollege.on.worldcat.org\/oclc\/5959304\" target=\"_blank\" rel=\"noopener\"><strong>K218.E9 S33<\/strong><\/a><\/p>\n<p>Contains marginalia, underlining and marginal lining.<br \/>\nPDF Information:\u00a019 pages &#8211; 13mb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schmitt, Carl Die Lage der Europ\u00e4ischen Rechtswissenschaft T\u00fcbingen, Internationaler Universit\u00e4ts-Verlag, 1950 Call #:\u00a0K218.E9 S33 Contains marginalia, underlining and marginal lining. PDF Information:\u00a019 pages &#8211; 13mb<\/p>\n","protected":false},"author":500,"featured_media":808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Schmitt, Carl Die Lage der Europ\u00e4ischen Rechtswissenschaft T\u00fcbingen, Internationaler Universit\u00e4ts-Verlag, 1950 Call #:\u00a0K218.E9 S33 Contains marginalia, underlining and marginal lining. PDF Information:\u00a019 pages &#8211; 13mb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-14T20:07:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T15:35:51+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png\" \/>\n\t<meta property=\"og:image:width\" content=\"402\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"meghan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"meghan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/\"},\"author\":{\"name\":\"meghan\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\"},\"headline\":\"Schmitt, Carl &#8211; Die Lage der Europ\u00e4ischen Rechtswissenschaft\",\"datePublished\":\"2016-04-14T20:07:43+00:00\",\"dateModified\":\"2025-08-11T15:35:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/\"},\"wordCount\":37,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/Schmitt-Die-Lage-Der-Europaischen.png\",\"articleSection\":[\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/\",\"name\":\"Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/Schmitt-Die-Lage-Der-Europaischen.png\",\"datePublished\":\"2016-04-14T20:07:43+00:00\",\"dateModified\":\"2025-08-11T15:35:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/Schmitt-Die-Lage-Der-Europaischen.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/Schmitt-Die-Lage-Der-Europaischen.png\",\"width\":402,\"height\":588},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmitt, Carl &#8211; Die Lage der Europ\u00e4ischen Rechtswissenschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\",\"name\":\"meghan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"caption\":\"meghan\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/meghan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/","og_locale":"en_US","og_type":"article","og_title":"Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library","og_description":"Schmitt, Carl Die Lage der Europ\u00e4ischen Rechtswissenschaft T\u00fcbingen, Internationaler Universit\u00e4ts-Verlag, 1950 Call #:\u00a0K218.E9 S33 Contains marginalia, underlining and marginal lining. PDF Information:\u00a019 pages &#8211; 13mb","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2016-04-14T20:07:43+00:00","article_modified_time":"2025-08-11T15:35:51+00:00","og_image":[{"width":402,"height":588,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","type":"image\/png"}],"author":"meghan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"meghan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/"},"author":{"name":"meghan","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88"},"headline":"Schmitt, Carl &#8211; Die Lage der Europ\u00e4ischen Rechtswissenschaft","datePublished":"2016-04-14T20:07:43+00:00","dateModified":"2025-08-11T15:35:51+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/"},"wordCount":37,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","articleSection":["Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/","name":"Schmitt, Carl - Die Lage der Europ\u00e4ischen Rechtswissenschaft - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","datePublished":"2016-04-14T20:07:43+00:00","dateModified":"2025-08-11T15:35:51+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","width":402,"height":588},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/schmitt-carl-die-lage-der-europaischen-rechtswissenschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Schmitt, Carl &#8211; Die Lage der Europ\u00e4ischen Rechtswissenschaft"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88","name":"meghan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","caption":"meghan"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/meghan\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/Schmitt-Die-Lage-Der-Europaischen.png","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/500"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":8,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"predecessor-version":[{"id":5307,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/537\/revisions\/5307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/808"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}