{"id":5010,"date":"2024-09-30T15:34:59","date_gmt":"2024-09-30T19:34:59","guid":{"rendered":"https:\/\/blogs.bard.edu\/arendtcollection\/?p=5010"},"modified":"2024-09-30T15:34:59","modified_gmt":"2024-09-30T19:34:59","slug":"sorel-georges-les-illusions-du-progres","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/","title":{"rendered":"Sorel, Georges &#8211; Les illusions du progr\u00e8s"},"content":{"rendered":"<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/09\/Sorel-Lesillusionsduprogres.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5011\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\" alt=\"\" width=\"181\" height=\"300\" \/><\/a><\/h2>\n<h2><span data-sheets-root=\"1\">Sorel, Georges<\/span><\/h2>\n<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/09\/Sorel-Lesillusionsduprogres.pdf\"><span data-sheets-root=\"1\">Les illusions du progr\u00e8s<\/span><\/a><\/h2>\n<p><span class=\"MuiTypography-root MuiTypography-body1\" dir=\"auto\" data-testid=\"item-detail-record-publisher-678571-0\"><span data-testid=\"highlighted-term-container\">Paris, M. Rivie\u0300re, 1947<\/span><\/span><\/p>\n<p>Call#: <a href=\"https:\/\/bardcollege.on.worldcat.org\/search\/detail\/678571?queryString=Les%20illusions%20du%20progr%C3%A8s&amp;clusterResults=false&amp;groupVariantRecords=false&amp;subscope=wz%3A624%3A%3Asz%3A39773&amp;changedFacet=scope\">HM101 .S7 1947<\/a><\/p>\n<div class=\"MuiGrid-root jss653 MuiGrid-item MuiGrid-grid-xs-12 MuiGrid-grid-md-9\">\n<div class=\"MuiBox-root jss667\">\n<p class=\"MuiTypography-root MuiTypography-body1\" data-testid=\"local-notes-0\"><span data-testid=\"highlighted-term-container\">Contains underlining,marginal lining, and endpaper notes<\/span><\/p>\n<p data-testid=\"local-notes-0\">PDF Information: 18 pages &#8211; 806 KB<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorel, Georges Les illusions du progr\u00e8s Paris, M. Rivie\u0300re, 1947 Call#: HM101 .S7 1947 Contains underlining,marginal lining, and endpaper notes PDF Information: 18 pages &#8211; 806 KB &nbsp;<\/p>\n","protected":false},"author":1554,"featured_media":5011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-5010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arendt-collection","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Sorel, Georges Les illusions du progr\u00e8s Paris, M. Rivie\u0300re, 1947 Call#: HM101 .S7 1947 Contains underlining,marginal lining, and endpaper notes PDF Information: 18 pages &#8211; 806 KB &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T19:34:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\" \/>\n\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"bosgang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bosgang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/\"},\"author\":{\"name\":\"bosgang\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"headline\":\"Sorel, Georges &#8211; Les illusions du progr\u00e8s\",\"datePublished\":\"2024-09-30T19:34:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/\"},\"wordCount\":35,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\",\"articleSection\":[\"Arendt Collection\",\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/\",\"name\":\"Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\",\"datePublished\":\"2024-09-30T19:34:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png\",\"width\":181,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-les-illusions-du-progres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sorel, Georges &#8211; Les illusions du progr\u00e8s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\",\"name\":\"bosgang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"caption\":\"bosgang\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/bosgang\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/","og_locale":"en_US","og_type":"article","og_title":"Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library","og_description":"Sorel, Georges Les illusions du progr\u00e8s Paris, M. Rivie\u0300re, 1947 Call#: HM101 .S7 1947 Contains underlining,marginal lining, and endpaper notes PDF Information: 18 pages &#8211; 806 KB &nbsp;","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2024-09-30T19:34:59+00:00","og_image":[{"width":181,"height":300,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","type":"image\/png"}],"author":"bosgang","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bosgang","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/"},"author":{"name":"bosgang","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"headline":"Sorel, Georges &#8211; Les illusions du progr\u00e8s","datePublished":"2024-09-30T19:34:59+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/"},"wordCount":35,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","articleSection":["Arendt Collection","Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/","name":"Sorel, Georges - Les illusions du progr\u00e8s - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","datePublished":"2024-09-30T19:34:59+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","width":181,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-les-illusions-du-progres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Sorel, Georges &#8211; Les illusions du progr\u00e8s"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74","name":"bosgang","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","caption":"bosgang"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/bosgang\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/bc_Arendt_Sorel_LesIllusionsduProgres_Cover_001.png","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/5010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/1554"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=5010"}],"version-history":[{"count":1,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/5010\/revisions"}],"predecessor-version":[{"id":5012,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/5010\/revisions\/5012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/5011"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=5010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=5010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=5010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}