{"id":4978,"date":"2024-09-18T14:03:08","date_gmt":"2024-09-18T18:03:08","guid":{"rendered":"https:\/\/blogs.bard.edu\/arendtcollection\/?p=4978"},"modified":"2024-09-18T14:48:44","modified_gmt":"2024-09-18T18:48:44","slug":"sorel-georges-uber-die-gewalt","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/","title":{"rendered":"Sorel, Georges &#8211; U\u0308ber die Gewalt"},"content":{"rendered":"<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/09\/Sorel-UberdieGewalt.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4979\" style=\"font-size: 16px\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg\" alt=\"\" width=\"189\" height=\"300\" \/><\/a><\/h2>\n<h2>Sorel, Georges<\/h2>\n<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/09\/Sorel-UberdieGewalt.pdf\">U\u0308ber die Gewalt<\/a><\/h2>\n<p>Innsbruck : Universita\u0308ts-Vergal Wagner, 1928<\/p>\n<p>Call#: <a href=\"https:\/\/bardcollege.on.worldcat.org\/search\/detail\/20720663?queryString=U%CC%88ber%20die%20Gewalt&amp;clusterResults=true&amp;groupVariantRecords=false&amp;stickyFacetsChecked=true&amp;subscope=wz%3A624%3A%3Asz%3A39773&amp;changedFacet=scope\">HD6477 .S674 1928<\/a><\/p>\n<p>Contains marginalia, underlining, marginal lining and endpaper notes<\/p>\n<p>PDF Information: 121 pages &#8211; 9.8 MB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorel, Georges U\u0308ber die Gewalt Innsbruck : Universita\u0308ts-Vergal Wagner, 1928 Call#: HD6477 .S674 1928 Contains marginalia, underlining, marginal lining and endpaper notes PDF Information: 121 pages &#8211; 9.8 MB<\/p>\n","protected":false},"author":1554,"featured_media":4979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-4978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arendt-collection","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Sorel, Georges U\u0308ber die Gewalt Innsbruck : Universita\u0308ts-Vergal Wagner, 1928 Call#: HD6477 .S674 1928 Contains marginalia, underlining, marginal lining and endpaper notes PDF Information: 121 pages &#8211; 9.8 MB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-18T18:03:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T18:48:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"189\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bosgang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bosgang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/\"},\"author\":{\"name\":\"bosgang\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"headline\":\"Sorel, Georges &#8211; U\u0308ber die Gewalt\",\"datePublished\":\"2024-09-18T18:03:08+00:00\",\"dateModified\":\"2024-09-18T18:48:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Sorel_UberdieGewalt.jpg\",\"articleSection\":[\"Arendt Collection\",\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/\",\"name\":\"Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Sorel_UberdieGewalt.jpg\",\"datePublished\":\"2024-09-18T18:03:08+00:00\",\"dateModified\":\"2024-09-18T18:48:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Sorel_UberdieGewalt.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Sorel_UberdieGewalt.jpg\",\"width\":189,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/sorel-georges-uber-die-gewalt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sorel, Georges &#8211; U\u0308ber die Gewalt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\",\"name\":\"bosgang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"caption\":\"bosgang\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/bosgang\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/","og_locale":"en_US","og_type":"article","og_title":"Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library","og_description":"Sorel, Georges U\u0308ber die Gewalt Innsbruck : Universita\u0308ts-Vergal Wagner, 1928 Call#: HD6477 .S674 1928 Contains marginalia, underlining, marginal lining and endpaper notes PDF Information: 121 pages &#8211; 9.8 MB","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2024-09-18T18:03:08+00:00","article_modified_time":"2024-09-18T18:48:44+00:00","og_image":[{"width":189,"height":300,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","type":"image\/jpeg"}],"author":"bosgang","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bosgang","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/"},"author":{"name":"bosgang","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"headline":"Sorel, Georges &#8211; U\u0308ber die Gewalt","datePublished":"2024-09-18T18:03:08+00:00","dateModified":"2024-09-18T18:48:44+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/"},"wordCount":33,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","articleSection":["Arendt Collection","Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/","name":"Sorel, Georges - U\u0308ber die Gewalt - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","datePublished":"2024-09-18T18:03:08+00:00","dateModified":"2024-09-18T18:48:44+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","width":189,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/sorel-georges-uber-die-gewalt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Sorel, Georges &#8211; U\u0308ber die Gewalt"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74","name":"bosgang","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","caption":"bosgang"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/bosgang\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Sorel_UberdieGewalt.jpg","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/1554"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=4978"}],"version-history":[{"count":3,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4978\/revisions"}],"predecessor-version":[{"id":4985,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4978\/revisions\/4985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/4979"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=4978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=4978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=4978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}