{"id":4958,"date":"2024-09-11T14:10:34","date_gmt":"2024-09-11T18:10:34","guid":{"rendered":"https:\/\/blogs.bard.edu\/arendtcollection\/?p=4958"},"modified":"2024-09-11T14:10:34","modified_gmt":"2024-09-11T18:10:34","slug":"gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/","title":{"rendered":"Gilbert, Felix &#8211; Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence"},"content":{"rendered":"<p><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/08\/Gilbert-Machiavelli_Guicciardini.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4959\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\" alt=\"\" width=\"229\" height=\"300\" \/><\/a><\/p>\n<h2>Gilbert, Felix<\/h2>\n<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2024\/08\/Gilbert-Machiavelli_Guicciardini.pdf\">Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence<\/a><\/h2>\n<p>Princeton, New Jersey : Princeton University Press, 1965.<\/p>\n<p>Call #: <a href=\"https:\/\/bardcollege.on.worldcat.org\/oclc\/405678\">DG738.13 .G5<\/a><\/p>\n<p>Contains marginalia, underlining and marginal lining<\/p>\n<p>PDF information: 121 pages &#8211; 10.4 MB<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilbert, Felix Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence Princeton, New Jersey : Princeton University Press, 1965. Call #: DG738.13 .G5 Contains marginalia, underlining and marginal lining PDF information: 121 pages &#8211; 10.4 MB &nbsp;<\/p>\n","protected":false},"author":1554,"featured_media":4959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-4958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arendt-collection","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Gilbert, Felix Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence Princeton, New Jersey : Princeton University Press, 1965. Call #: DG738.13 .G5 Contains marginalia, underlining and marginal lining PDF information: 121 pages &#8211; 10.4 MB &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-11T18:10:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"229\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bosgang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bosgang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/\"},\"author\":{\"name\":\"bosgang\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"headline\":\"Gilbert, Felix &#8211; Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence\",\"datePublished\":\"2024-09-11T18:10:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/\"},\"wordCount\":44,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\",\"articleSection\":[\"Arendt Collection\",\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/\",\"name\":\"Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\",\"datePublished\":\"2024-09-11T18:10:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2024\\\/09\\\/Gilbert-Machiavelli_Guicciardinicover-1.jpg\",\"width\":229,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gilbert, Felix &#8211; Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/f38abc90ee057a013141071ab4ae5f74\",\"name\":\"bosgang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g\",\"caption\":\"bosgang\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/bosgang\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/","og_locale":"en_US","og_type":"article","og_title":"Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library","og_description":"Gilbert, Felix Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence Princeton, New Jersey : Princeton University Press, 1965. Call #: DG738.13 .G5 Contains marginalia, underlining and marginal lining PDF information: 121 pages &#8211; 10.4 MB &nbsp;","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2024-09-11T18:10:34+00:00","og_image":[{"width":229,"height":300,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","type":"image\/jpeg"}],"author":"bosgang","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bosgang","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/"},"author":{"name":"bosgang","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"headline":"Gilbert, Felix &#8211; Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence","datePublished":"2024-09-11T18:10:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/"},"wordCount":44,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","articleSection":["Arendt Collection","Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/","name":"Gilbert, Felix - Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","datePublished":"2024-09-11T18:10:34+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","width":229,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/gilbert-felix-machiavelli-and-guicciardini-politics-and-history-in-sixteenth-century-florence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Gilbert, Felix &#8211; Machiavelli and Guicciardini: Politics and History in Sixteenth-Century Florence"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/f38abc90ee057a013141071ab4ae5f74","name":"bosgang","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083395029e24f8d96ac39092e8b85cb9ed25fefc007e469f2a4efab31f5b33de?s=96&r=g","caption":"bosgang"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/bosgang\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2024\/09\/Gilbert-Machiavelli_Guicciardinicover-1.jpg","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/1554"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=4958"}],"version-history":[{"count":1,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4958\/revisions"}],"predecessor-version":[{"id":4960,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4958\/revisions\/4960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/4959"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=4958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=4958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=4958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}