{"id":4038,"date":"2023-11-08T17:44:04","date_gmt":"2023-11-08T22:44:04","guid":{"rendered":"https:\/\/blogs.bard.edu\/arendtcollection\/?p=4038"},"modified":"2024-06-27T15:39:26","modified_gmt":"2024-06-27T19:39:26","slug":"brod-max-franz-kafka-eine-biographie","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/","title":{"rendered":"Brod, Max &#8211; Franz Kafka, eine Biographie"},"content":{"rendered":"<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2023\/10\/Brod-FranzKafkaEineBiographie.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4039\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\" alt=\"\" width=\"208\" height=\"300\" \/><\/a><\/h2>\n<h2>Brod, Max<\/h2>\n<h2><a href=\"https:\/\/www.bard.edu\/library\/pdfs\/archives\/2023\/10\/Brod-FranzKafkaEineBiographie.pdf\">Franz Kafka, eine Biographie (erinnerungen und dokumente)<\/a><\/h2>\n<p>New York, Schocken Books [1946]<\/p>\n<p>Call #: <a href=\"https:\/\/bardcollege.on.worldcat.org\/oclc\/70343766\">PT2621 .A25 Z7 B86 1946<\/a><\/p>\n<p>Arendt copy contains endpaper notes<\/p>\n<p>PDF Information: 15 pages &#8211; 1,853KB<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brod, Max Franz Kafka, eine Biographie (erinnerungen und dokumente) New York, Schocken Books [1946] Call #: PT2621 .A25 Z7 B86 1946 Arendt copy contains endpaper notes PDF Information: 15 pages &#8211; 1,853KB<\/p>\n","protected":false},"author":1555,"featured_media":4039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,13],"tags":[],"class_list":["post-4038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arendt-collection","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Brod, Max Franz Kafka, eine Biographie (erinnerungen und dokumente) New York, Schocken Books [1946] Call #: PT2621 .A25 Z7 B86 1946 Arendt copy contains endpaper notes PDF Information: 15 pages &#8211; 1,853KB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T22:44:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-27T19:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"208\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"tieger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"tieger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/\"},\"author\":{\"name\":\"tieger\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/53ed3e8a362d35d91b5bf9e2975c3ecb\"},\"headline\":\"Brod, Max &#8211; Franz Kafka, eine Biographie\",\"datePublished\":\"2023-11-08T22:44:04+00:00\",\"dateModified\":\"2024-06-27T19:39:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/\"},\"wordCount\":35,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2023\\\/11\\\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\",\"articleSection\":[\"Arendt Collection\",\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/\",\"name\":\"Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2023\\\/11\\\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\",\"datePublished\":\"2023-11-08T22:44:04+00:00\",\"dateModified\":\"2024-06-27T19:39:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/53ed3e8a362d35d91b5bf9e2975c3ecb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2023\\\/11\\\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2023\\\/11\\\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg\",\"width\":208,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/brod-max-franz-kafka-eine-biographie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brod, Max &#8211; Franz Kafka, eine Biographie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/53ed3e8a362d35d91b5bf9e2975c3ecb\",\"name\":\"tieger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g\",\"caption\":\"tieger\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/tieger\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/","og_locale":"en_US","og_type":"article","og_title":"Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library","og_description":"Brod, Max Franz Kafka, eine Biographie (erinnerungen und dokumente) New York, Schocken Books [1946] Call #: PT2621 .A25 Z7 B86 1946 Arendt copy contains endpaper notes PDF Information: 15 pages &#8211; 1,853KB","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2023-11-08T22:44:04+00:00","article_modified_time":"2024-06-27T19:39:26+00:00","og_image":[{"width":208,"height":300,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","type":"image\/jpeg"}],"author":"tieger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"tieger","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/"},"author":{"name":"tieger","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/53ed3e8a362d35d91b5bf9e2975c3ecb"},"headline":"Brod, Max &#8211; Franz Kafka, eine Biographie","datePublished":"2023-11-08T22:44:04+00:00","dateModified":"2024-06-27T19:39:26+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/"},"wordCount":35,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","articleSection":["Arendt Collection","Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/","name":"Brod, Max - Franz Kafka, eine Biographie - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","datePublished":"2023-11-08T22:44:04+00:00","dateModified":"2024-06-27T19:39:26+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/53ed3e8a362d35d91b5bf9e2975c3ecb"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","width":208,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/brod-max-franz-kafka-eine-biographie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Brod, Max &#8211; Franz Kafka, eine Biographie"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/53ed3e8a362d35d91b5bf9e2975c3ecb","name":"tieger","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/619641b4d0a5d8a1d530f58592e9fde72b92d233377b940fa2f71c15a32c2f67?s=96&r=g","caption":"tieger"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/tieger\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2023\/11\/bc_Arendt_Brod_FranzKafkaEineBiographie_cover_01.jpg","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/1555"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=4038"}],"version-history":[{"count":2,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4038\/revisions"}],"predecessor-version":[{"id":4342,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/4038\/revisions\/4342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/4039"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=4038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=4038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=4038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}