{"id":241,"date":"2016-04-12T19:26:30","date_gmt":"2016-04-12T19:26:30","guid":{"rendered":"http:\/\/blogs.bard.edu\/arendtcollection\/?p=241"},"modified":"2024-07-10T15:53:08","modified_gmt":"2024-07-10T19:53:08","slug":"heidegger-martin-der-europaische-nihilismus","status":"publish","type":"post","link":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/","title":{"rendered":"Heidegger, Martin &#8211; Der Europ\u00e4ische Nihilismus"},"content":{"rendered":"<p><a href=\"http:\/\/www.bard.edu\/library\/arendt\/pdfs\/Heidegger-Nihilismus.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-996\" src=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische-194x300.png\" alt=\"heidegger-der-europaische\" width=\"194\" height=\"300\" srcset=\"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische-194x300.png 194w, https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png 408w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/a><\/p>\n<h2>Heidegger, Martin<br \/>\n<strong><a href=\"http:\/\/www.bard.edu\/library\/arendt\/pdfs\/Heidegger-Nihilismus.pdf\" target=\"_blank\" rel=\"noopener\">Der Europ\u00e4ische Nihilismus<\/a><\/strong><\/h2>\n<p>Pfullingen, Neske, 1967<br \/>\nCall #:\u00a0<a href=\"https:\/\/bardcollege.on.worldcat.org\/oclc\/883084\" target=\"_blank\" rel=\"noopener\"><strong>B3279.H48 E9<\/strong><\/a><\/p>\n<p>Contains marginalia, underlining, marginal lining, and is inscribed by author.<br \/>\nPDF Information:\u00a0167 pages &#8211; 58 mb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heidegger, Martin Der Europ\u00e4ische Nihilismus Pfullingen, Neske, 1967 Call #:\u00a0B3279.H48 E9 Contains marginalia, underlining, marginal lining, and is inscribed by author. PDF Information:\u00a0167 pages &#8211; 58 mb<\/p>\n","protected":false},"author":500,"featured_media":996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marginalia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library\" \/>\n<meta property=\"og:description\" content=\"Heidegger, Martin Der Europ\u00e4ische Nihilismus Pfullingen, Neske, 1967 Call #:\u00a0B3279.H48 E9 Contains marginalia, underlining, marginal lining, and is inscribed by author. PDF Information:\u00a0167 pages &#8211; 58 mb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/\" \/>\n<meta property=\"og:site_name\" content=\"Hannah Arendt Personal Library\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-12T19:26:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-10T19:53:08+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png\" \/>\n\t<meta property=\"og:image:width\" content=\"408\" \/>\n\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"meghan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"meghan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/\"},\"author\":{\"name\":\"meghan\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\"},\"headline\":\"Heidegger, Martin &#8211; Der Europ\u00e4ische Nihilismus\",\"datePublished\":\"2016-04-12T19:26:30+00:00\",\"dateModified\":\"2024-07-10T19:53:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/\"},\"wordCount\":34,\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/heidegger-der-europaische.png\",\"articleSection\":[\"Marginalia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/\",\"name\":\"Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/heidegger-der-europaische.png\",\"datePublished\":\"2016-04-12T19:26:30+00:00\",\"dateModified\":\"2024-07-10T19:53:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/heidegger-der-europaische.png\",\"contentUrl\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/files\\\/2016\\\/04\\\/heidegger-der-europaische.png\",\"width\":408,\"height\":631},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/heidegger-martin-der-europaische-nihilismus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heidegger, Martin &#8211; Der Europ\u00e4ische Nihilismus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#website\",\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/\",\"name\":\"Hannah Arendt Personal Library\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/#\\\/schema\\\/person\\\/2f0091f47c833c1623a7bfe93cf0bd88\",\"name\":\"meghan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g\",\"caption\":\"meghan\"},\"url\":\"https:\\\/\\\/blogs.bard.edu\\\/arendtcollection\\\/author\\\/meghan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/","og_locale":"en_US","og_type":"article","og_title":"Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library","og_description":"Heidegger, Martin Der Europ\u00e4ische Nihilismus Pfullingen, Neske, 1967 Call #:\u00a0B3279.H48 E9 Contains marginalia, underlining, marginal lining, and is inscribed by author. PDF Information:\u00a0167 pages &#8211; 58 mb","og_url":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/","og_site_name":"Hannah Arendt Personal Library","article_published_time":"2016-04-12T19:26:30+00:00","article_modified_time":"2024-07-10T19:53:08+00:00","og_image":[{"width":408,"height":631,"url":"http:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","type":"image\/png"}],"author":"meghan","twitter_card":"summary_large_image","twitter_misc":{"Written by":"meghan","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#article","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/"},"author":{"name":"meghan","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88"},"headline":"Heidegger, Martin &#8211; Der Europ\u00e4ische Nihilismus","datePublished":"2016-04-12T19:26:30+00:00","dateModified":"2024-07-10T19:53:08+00:00","mainEntityOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/"},"wordCount":34,"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","articleSection":["Marginalia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/","url":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/","name":"Heidegger, Martin - Der Europ\u00e4ische Nihilismus - Hannah Arendt Personal Library","isPartOf":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#primaryimage"},"image":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#primaryimage"},"thumbnailUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","datePublished":"2016-04-12T19:26:30+00:00","dateModified":"2024-07-10T19:53:08+00:00","author":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88"},"breadcrumb":{"@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#primaryimage","url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","contentUrl":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","width":408,"height":631},{"@type":"BreadcrumbList","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/heidegger-martin-der-europaische-nihilismus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blogs.bard.edu\/arendtcollection\/"},{"@type":"ListItem","position":2,"name":"Heidegger, Martin &#8211; Der Europ\u00e4ische Nihilismus"}]},{"@type":"WebSite","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#website","url":"https:\/\/blogs.bard.edu\/arendtcollection\/","name":"Hannah Arendt Personal Library","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blogs.bard.edu\/arendtcollection\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/blogs.bard.edu\/arendtcollection\/#\/schema\/person\/2f0091f47c833c1623a7bfe93cf0bd88","name":"meghan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c1d57c8d8584e23a5d0e04560a1ccb89238cbd6cc0f49c9f9d032a149f6dcac?s=96&r=g","caption":"meghan"},"url":"https:\/\/blogs.bard.edu\/arendtcollection\/author\/meghan\/"}]}},"jetpack_featured_media_url":"https:\/\/blogs.bard.edu\/arendtcollection\/files\/2016\/04\/heidegger-der-europaische.png","_links":{"self":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/users\/500"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/comments?post=241"}],"version-history":[{"count":8,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/241\/revisions"}],"predecessor-version":[{"id":4513,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/posts\/241\/revisions\/4513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media\/996"}],"wp:attachment":[{"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/media?parent=241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/categories?post=241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.bard.edu\/arendtcollection\/wp-json\/wp\/v2\/tags?post=241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}